{"id":67711,"count":1,"description":"","link":"http:\/\/www.citypainter.in\/cp\/tag\/colour-combination-in-punjab-khor","name":"colour combination in Punjab Khor","slug":"colour-combination-in-punjab-khor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.citypainter.in\/cp\/wp-json\/wp\/v2\/tags\/67711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.citypainter.in\/cp\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.citypainter.in\/cp\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.citypainter.in\/cp\/wp-json\/wp\/v2\/posts?tags=67711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}